{"id":1496,"date":"2013-02-08T11:53:31","date_gmt":"2013-02-08T09:53:31","guid":{"rendered":"http:\/\/www.kanaren-virtuell.de\/news\/?p=1496"},"modified":"2013-10-26T11:54:00","modified_gmt":"2013-10-26T09:54:00","slug":"tegueste-gefuehrte-wanderung-ins-anagagebirge-auf-teneriffa","status":"publish","type":"post","link":"https:\/\/www.kanaren-virtuell.de\/news\/tegueste-gefuehrte-wanderung-ins-anagagebirge-auf-teneriffa\/","title":{"rendered":"Tegueste \u2013 Gef\u00fchrte Wanderung ins Anagagebirge auf Teneriffa"},"content":{"rendered":"<p>Der Ort Tegueste liegt im Nordosten Teneriffas und wird als Nachbargemeinde des Urlaubsortes San Cristobal de La Laguna ebenfalls oft von Touristen besucht. Urlauber, die die Insel auch gerne auf Schusters Rappen erkunden, k\u00f6nnten am kommenden Wochenende in Tegueste auf ihre Kosten kommen. Am 9. Februar wird in der Gemeinde eine gef\u00fchrte Wanderung angeboten, die um 9 Uhr an der Plaza de San Marcos startet. <\/p>\n<p>Die etwa 4-st\u00fcndige <a href=\"http:\/\/www.kanaren-virtuell.de\/teneriffa_2\/wandern\/index_wandern.htm\">Wandertour<\/a> f\u00fchrt \u00fcber La Degollada, Mesa de Tejina und La Orilla durch die <a href=\"http:\/\/www.kanaren-virtuell.de\/teneriffa_2\/orte\/anaga.htm\">kontrastreichen Landschaften des Anagagebirges<\/a>. Teilnehmer m\u00fcssen eine Geb\u00fchr in H\u00f6he von 5 Euro bezahlen. Interessierte k\u00f6nnen sich unter turismo@tegueste.org anmelden. <\/p>\n<p> <img decoding=\"async\" src=\"http:\/\/www.kanaren-virtuell.de\/teneriffa_2\/bilder-fotos\/teneriffa-anagagebirge-wanderwegweiser-tf12_1331.jpg\" alt=\"Wandern im Anagagebirge auf Teneriffa\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Ort Tegueste liegt im Nordosten Teneriffas und wird als Nachbargemeinde des Urlaubsortes San Cristobal de La Laguna ebenfalls oft von Touristen besucht. Urlauber, die die Insel auch gerne auf Schusters Rappen erkunden, k\u00f6nnten am kommenden Wochenende in Tegueste auf ihre Kosten kommen. Am 9. Februar wird in der Gemeinde eine gef\u00fchrte Wanderung angeboten, die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,22],"tags":[],"class_list":["post-1496","post","type-post","status-publish","format-standard","hentry","category-teneriffa","category-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts\/1496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/comments?post=1496"}],"version-history":[{"count":1,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts\/1496\/revisions"}],"predecessor-version":[{"id":1497,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts\/1496\/revisions\/1497"}],"wp:attachment":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/media?parent=1496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/categories?post=1496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/tags?post=1496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}