{"id":819,"date":"2011-02-24T11:37:25","date_gmt":"2011-02-24T09:37:25","guid":{"rendered":"http:\/\/www.kanaren-virtuell.de\/news\/?p=819"},"modified":"2013-10-24T11:37:58","modified_gmt":"2013-10-24T09:37:58","slug":"teide-nationalpark-kostenlose-fuehrung-nutzen","status":"publish","type":"post","link":"https:\/\/www.kanaren-virtuell.de\/news\/teide-nationalpark-kostenlose-fuehrung-nutzen\/","title":{"rendered":"Teide Nationalpark \u2013 Kostenlose F\u00fchrung nutzen"},"content":{"rendered":"<p>Der <a href=\"http:\/\/www.kanaren-virtuell.de\/teneriffa_2\/orte\/canadas.htm\">Teide Nationalpark auf Teneriffa<\/a> ist eines der beliebtesten Touristenziele der Insel, das j\u00e4hrlich rund drei Millionen Besucher anlockt. Ein weitverzweigtes Wegenetz entf\u00fchrt Aktivurlauber auf insgesamt 80 Routen in eine beeindruckende Bergwelt, die zahlreiche, landschaftliche Highlights zu bieten hat. Vier der Wanderwege erm\u00f6glichen auch behinderten Menschen, den vielseitigen Nationalpark zu erkunden. Urlauber k\u00f6nnen derzeit auch an kostenlosen F\u00fchrungen durch den Park teilnehmen. <\/p>\n<p>Die Gratis-F\u00fchrung startet am Mirador de la Ruleta und f\u00fchrt durch das Gebiet der Roques de Garcia. Ein ortskundiger Guide f\u00fchrt Interessierte t\u00e4glich zwischen 10.30 Uhr und 14.30 Uhr durch das kontrastreiche Areal und vermittelt ihnen Wissenswertes \u00fcber die sch\u00fctzenswerten Naturr\u00e4ume der Insel Teneriffa. Wer den Nationalpark auf eigene Faust erkunden m\u00f6chte, kann unter reservaparquesnacionales.es auch eine Erlaubnis zum Aufstieg auf den <a href=\"http:\/\/www.kanaren-virtuell.de\/teneriffa_2\/orte\/teide.htm\">Pico del Teide<\/a> beantragen. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Teide Nationalpark auf Teneriffa ist eines der beliebtesten Touristenziele der Insel, das j\u00e4hrlich rund drei Millionen Besucher anlockt. Ein weitverzweigtes Wegenetz entf\u00fchrt Aktivurlauber auf insgesamt 80 Routen in eine beeindruckende Bergwelt, die zahlreiche, landschaftliche Highlights zu bieten hat. Vier der Wanderwege erm\u00f6glichen auch behinderten Menschen, den vielseitigen Nationalpark zu erkunden. Urlauber k\u00f6nnen derzeit auch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-819","post","type-post","status-publish","format-standard","hentry","category-teneriffa"],"_links":{"self":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts\/819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":1,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"predecessor-version":[{"id":820,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/posts\/819\/revisions\/820"}],"wp:attachment":[{"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kanaren-virtuell.de\/news\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}